{"id":3197,"date":"2018-06-26T19:33:39","date_gmt":"2018-06-26T19:33:39","guid":{"rendered":"http:\/\/www.minevaganti.org\/?p=3197"},"modified":"2024-04-18T18:08:37","modified_gmt":"2024-04-18T17:08:37","slug":"grundtvig-workshop-inclusive-methods","status":"publish","type":"post","link":"https:\/\/minevaganti.org\/it\/grundtvig-workshop-inclusive-methods\/","title":{"rendered":"Grundtvig Workshop &#8220;Inclusive Methods on Foreign Language&#8221;"},"content":{"rendered":"<h2 class=\"MsoNormal\" style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\"Metodi inclusivi per la lingua straniera\"<\/strong><\/span><\/h2>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">L'obiettivo del workshop Grundtvig organizzato nel settembre 2013 da MVNGO era quello di sviluppare le competenze individuali e sociali dei partecipanti, in base alle loro esigenze di sviluppo personale e di apprendimento. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">Durante il workshop sono state potenziate la creativit\u00e0, la capacit\u00e0 di lavorare in gruppo, la fiducia in se stessi e la predisposizione alla collaborazione con gli altri.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">L'educazione non formale ha avuto un'influenza positiva su persone con background culturali e sociali molto diversi, quindi pu\u00f2 essere utilizzata come strumento nel processo educativo, fornendo lo sviluppo di competenze per l'autostima personale. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">Le attivit\u00e0 principali del workshop sono state pianificate seguendo il prototipo del metodo di simulazione.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">Il programma del workshop consisteva in quattro parti diverse, in cui i partecipanti avevano un ruolo attivo: dovevano trovare una soluzione a diversi tipi di problemi emersi durante le sessioni in classe su diversi argomenti: dialogo interculturale, difficolt\u00e0 di comprensione, comportamento culturale e barriere linguistiche.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">Ogni insegnante pu\u00f2 trovarsi ad affrontare problemi durante il suo lavoro quotidiano.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">L'obiettivo era quello di creare \"lezioni adattive\" in base alle diverse capacit\u00e0 degli studenti di interagire o comprendere un'altra lingua.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">Le attivit\u00e0 principali del progetto si sono basate sull'uso dell'educazione non formale come metodo di supporto per facilitare il processo di apprendimento di una lingua da parte degli stranieri.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">L'introduzione dell'istruzione NFE e dei metodi NFE ha contribuito a promuovere l'istruzione basata sui contenuti comunitari all'interno del sistema educativo formale, in quanto:<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">-Coinvolge attivamente gli studenti nell'identificazione dei bisogni e nella ricerca di soluzioni,<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">-Promuove un apprendimento pratico, flessibile e basato su esigenze reali,<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">-Si concentra sul miglioramento della vita dell'individuo e\/o della comunit\u00e0,<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">-Incoraggia gli studenti a valutare, esercitare e riflettere sul proprio apprendimento,<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><span style=\"font-size: 11pt;\">-Promuove l'uso dell'NFE come processo facilitatore durante la sessione di lavoro.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify; mso-layout-grid-align: none; text-autospace: none;\"><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"225\" class=\"alignnone size-medium wp-image-13635\" src=\"http:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3935-300x225.jpg\" alt=\"\" srcset=\"https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3935-300x225.jpg 300w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3935-768x576.jpg 768w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3935-1024x768.jpg 1024w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3935-958x719.jpg 958w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3935-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" width=\"300\" height=\"225\" class=\"alignnone size-medium wp-image-13636\" src=\"http:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3975-300x225.jpg\" alt=\"\" srcset=\"https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3975-300x225.jpg 300w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3975-768x576.jpg 768w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3975-1024x768.jpg 1024w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3975-958x719.jpg 958w, https:\/\/minevaganti.org\/wp-content\/uploads\/2013\/11\/IMG_3975-600x450.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><iframe src=\"\/\/www.youtube.com\/embed\/p4we8LWPppY\" width=\"640\" height=\"480\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Inclusive Methods on Foreign Language The aim of the Grundtvig Workshop organised in September 2013 by MVNGO was to develop participants\u2019 individual and social skills, relevant to their personal development and learning needs. During the workshop, the participants\u2019 creativity, teamwork skills, self-confidence and readiness for collaboration with others was enhanced. Non formal education had a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5172,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[383],"tags":[],"class_list":["post-3197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grundtvig-en","entry","has-media"],"_links":{"self":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts\/3197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/comments?post=3197"}],"version-history":[{"count":7,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts\/3197\/revisions"}],"predecessor-version":[{"id":42814,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts\/3197\/revisions\/42814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/media\/5172"}],"wp:attachment":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/media?parent=3197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/categories?post=3197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/tags?post=3197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}