{"id":22055,"date":"2020-06-08T18:46:50","date_gmt":"2020-06-08T15:46:50","guid":{"rendered":"https:\/\/engomvi.com\/?p=18566"},"modified":"2020-06-19T10:08:49","modified_gmt":"2020-06-19T10:08:49","slug":"mvi-eyf-new-genderaction","status":"publish","type":"post","link":"https:\/\/minevaganti.org\/it\/mvi-eyf-new-genderaction\/","title":{"rendered":"MVI EYF Workplan &#8220;New GenderAction&#8221; 2018"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"22055\" class=\"elementor elementor-22055\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-474461c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"474461c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f9fdc7f\" data-id=\"f9fdc7f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b631a9d elementor-widget elementor-widget-text-editor\" data-id=\"6b631a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p><strong><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-2046\" src=\"http:\/\/engomvi.com\/wp-content\/uploads\/2018\/07\/37692014_10155626337829327_451125656621678592_n-1024x1024.jpg\" alt=\"\" width=\"256\" height=\"256\" \/><span style=\"color: #000000;\">Attivit\u00e0 internazionale di sviluppo delle competenze \"New GenderAction<\/span><\/strong><br \/><span style=\"color: #000000;\"><strong>Sede: Varna, Bulgaria<\/strong><\/span><br \/><span style=\"color: #000000;\"><strong>Date: 20-25 luglio 2018<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">\"New GenderAction\" \u00e8 stata la seconda attivit\u00e0 internazionale di sviluppo delle competenze (SDA) del piano di lavoro internazionale 2018 del MV. L'attivit\u00e0 mirava a fornire ai partecipanti uno zaino complementare di conoscenze, competenze e metodologie per combattere il discorso d'odio di genere sui nuovi media, in un approccio complementare basato sull'interrelazione tra il discorso d'odio di genere e il discorso d'odio contro le categorie di migranti\/rifugiati (focus della prima SDA). Durante l'attivit\u00e0, i partecipanti hanno completato la progettazione del Manuale \"No Hate Speech in the Digital Era\", integrando la sua bozza con conoscenze e metodologie mirate a combattere l'hate speech di genere sui nuovi media.<\/span><br \/><span style=\"color: #000000;\">Allo stesso tempo, le metodologie prodotte in relazione ai discorsi d'odio contro i migranti e i rifugiati sono state riviste\/integrate sulla base delle conoscenze e degli approfondimenti specifici sulla dimensione di genere sviluppati nell'attivit\u00e0. Inoltre, i partecipanti hanno prodotto il progetto finale della campagna sociale \"Speak for Inclusion! rielaborando la bozza prodotta nel primo SDA.<\/span><\/p>\n<p><span style=\"color: #000000;\"><\/span><\/p>\n<p><span style=\"color: #000000;\"><\/span><\/p>\n<p><span style=\"color: #000000;\"><\/span><\/p>\n<p><span style=\"color: #000000;\"><\/span><\/p>\n<p><span style=\"color: #000000;\">In particolare, la SDA \"New GenderAction\" si rivolgeva a:<\/span><\/p>\n<p><span style=\"color: #000000;\">- Completare il processo di empowerment metodologico dei partecipanti fornendo loro consapevolezza, conoscenze, competenze e metodologie per contrastare l'hate speech di genere sui nuovi media.<\/span><br \/><span style=\"color: #000000;\">- Sviluppare la comprensione e le capacit\u00e0 educative dei partecipanti per affrontare l'interconnessione tra i discorsi d'odio basati sul genere e quelli contro le categorie di migranti e rifugiati.<\/span><br \/><span style=\"color: #000000;\">- Produrre un approccio metodologico completo per le organizzazioni giovanili in tutta l'area del CoE per contrastare le dimensioni del discorso d'odio legato ai migranti\/rifugiati e alla discriminazione di genere attraverso risorse educative onnicomprensive che abbraccino l'interconnessione tra questi ultimi fenomeni.<\/span><br \/><span style=\"color: #000000;\">- Progettare uno sforzo di sensibilizzazione ed educazione basato sull'azione dei nuovi media e sull'educazione diretta dei giovani, mirato a promuovere la consapevolezza dei giovani e degli stakeholder sui principi del no hate speech nell'ambito delle questioni di genere e dei rifugiati, sull'interconnessione tra questi ultimi e sull'impegno attivo nel contrastare i fenomeni di hate speech in modo globale.<\/span><\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>International Skill Development Activity \u201cNew GenderAction\u201dVenue: Varna, BulgariaDates: 20-25 July 2018 \u201cNew GenderAction\u201d was the second international Skills Development Activity (SDA) of MV International Work Plan 2018. The Activity was aimed at providing participants with a complementary backpack of knowledge, skills and methodologies to fight gender-based hate speech on new media, in a complementary approach [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22667,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[377],"tags":[],"class_list":["post-22055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eyf-en","entry","has-media"],"_links":{"self":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts\/22055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/comments?post=22055"}],"version-history":[{"count":10,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts\/22055\/revisions"}],"predecessor-version":[{"id":23538,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/posts\/22055\/revisions\/23538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/media\/22667"}],"wp:attachment":[{"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/media?parent=22055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/categories?post=22055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/minevaganti.org\/it\/wp-json\/wp\/v2\/tags?post=22055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}